{"id":115,"count":10,"description":"","link":"https:\/\/www.gtline.com\/en\/download-category\/mediakit\/","name":"Mediakit","slug":"mediakit","taxonomy":"download_category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mediakit | GT Line<\/title>\n<meta name=\"description\" content=\"Official brand assets for media and partners. Logos, visual identity and communication materials always aligned to GT Line guidelines.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gtline.com\/en\/download-category\/mediakit\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mediakit | GT Line\" \/>\n<meta property=\"og:description\" content=\"Official brand assets for media and partners. Logos, visual identity and communication materials always aligned to GT Line guidelines.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gtline.com\/en\/download-category\/mediakit\/\" \/>\n<meta property=\"og:site_name\" content=\"Gt Line\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/download-category\\\/mediakit\\\/\",\"url\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/download-category\\\/mediakit\\\/\",\"name\":\"Mediakit | GT Line\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/#website\"},\"description\":\"Official brand assets for media and partners. Logos, visual identity and communication materials always aligned to GT Line guidelines.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/download-category\\\/mediakit\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/download-category\\\/mediakit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mediakit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/\",\"name\":\"Gt Line\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/#organization\",\"name\":\"Gt Line\",\"url\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/GT-LINE-colors.png\",\"contentUrl\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/GT-LINE-colors.png\",\"width\":1084,\"height\":643,\"caption\":\"Gt Line\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gtline.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gtlinesrl?locale=it_IT\",\"https:\\\/\\\/www.instagram.com\\\/gt_line_srl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDvpkFqswNJOVFz64PkYRQQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gt-line-srl\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mediakit | GT Line","description":"Official brand assets for media and partners. Logos, visual identity and communication materials always aligned to GT Line guidelines.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gtline.com\/en\/download-category\/mediakit\/","og_locale":"en_US","og_type":"article","og_title":"Mediakit | GT Line","og_description":"Official brand assets for media and partners. Logos, visual identity and communication materials always aligned to GT Line guidelines.","og_url":"https:\/\/www.gtline.com\/en\/download-category\/mediakit\/","og_site_name":"Gt Line","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.gtline.com\/en\/download-category\/mediakit\/","url":"https:\/\/www.gtline.com\/en\/download-category\/mediakit\/","name":"Mediakit | GT Line","isPartOf":{"@id":"https:\/\/www.gtline.com\/en\/#website"},"description":"Official brand assets for media and partners. Logos, visual identity and communication materials always aligned to GT Line guidelines.","breadcrumb":{"@id":"https:\/\/www.gtline.com\/en\/download-category\/mediakit\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gtline.com\/en\/download-category\/mediakit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gtline.com\/en\/"},{"@type":"ListItem","position":2,"name":"Mediakit"}]},{"@type":"WebSite","@id":"https:\/\/www.gtline.com\/en\/#website","url":"https:\/\/www.gtline.com\/en\/","name":"Gt Line","description":"","publisher":{"@id":"https:\/\/www.gtline.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gtline.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.gtline.com\/en\/#organization","name":"Gt Line","url":"https:\/\/www.gtline.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.gtline.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.gtline.com\/en\/wp-content\/uploads\/sites\/3\/2025\/01\/GT-LINE-colors.png","contentUrl":"https:\/\/www.gtline.com\/en\/wp-content\/uploads\/sites\/3\/2025\/01\/GT-LINE-colors.png","width":1084,"height":643,"caption":"Gt Line"},"image":{"@id":"https:\/\/www.gtline.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gtlinesrl?locale=it_IT","https:\/\/www.instagram.com\/gt_line_srl\/","https:\/\/www.youtube.com\/channel\/UCDvpkFqswNJOVFz64PkYRQQ","https:\/\/www.linkedin.com\/company\/gt-line-srl\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.gtline.com\/en\/wp-json\/wp\/v2\/download_category\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gtline.com\/en\/wp-json\/wp\/v2\/download_category"}],"about":[{"href":"https:\/\/www.gtline.com\/en\/wp-json\/wp\/v2\/taxonomies\/download_category"}],"wp:post_type":[{"href":"https:\/\/www.gtline.com\/en\/wp-json\/wp\/v2\/downloads-list?download_category=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}